{"id":11060,"date":"2019-09-16T13:13:59","date_gmt":"2019-09-16T06:13:59","guid":{"rendered":"https:\/\/informatika.uin-malang.ac.id\/?p=11060"},"modified":"2019-09-16T13:13:59","modified_gmt":"2019-09-16T06:13:59","slug":"competitions-of-bi-corner-challenge-3-bicc-3","status":"publish","type":"post","link":"https:\/\/mit.uin-malang.ac.id\/en\/competitions-of-bi-corner-challenge-3-bicc-3\/","title":{"rendered":"Achievements at BI Corner Challenge 3 (BICC 3) 2019"},"content":{"rendered":"<div class=\"col-lg-12 col-md-12 col-sm-12 col-xs-12\">\n<p>Congratulation for the achievement at BI Corner Challenge 3 that was held on 1 July-10 September 2019 is addressed to:<\/p>\n<ol>\n<li>Moch. Afifuddin Zuhri\/15650005 as 1st Winner on Design Challenge<\/li>\n<li>Fuad Jauhari \/15650067 &amp; Hagar Prily Titania\/16650031 as 2nd Winner on Design Challenge<\/li>\n<li>Muhammad Ammarullah Ridho\/17650071 as 3rd Winner on Design Challenge<\/li>\n<li>Adito Wahyu Prakoso \/17650081, Duvan Deswantara Putra\/17650012 &amp; Muhammad Ammarullah Ridho\/17650071 as 3rd Winner on Vidio Edukasi<\/li>\n<\/ol>\n<p>BI Corner Challenge is a biannual competition in technological development to promote financial literacy supported by Bank Indonesia.<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4726.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-11061\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4726-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4733.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-11062\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4733-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4734.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-11063\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4734-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4735.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11064\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4735-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4736.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11065\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4736-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4737.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11066\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4737-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4743.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11067\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4743-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<td style=\"width: 50%;\"><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4745.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11068\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/IMG_4745-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/JUARA-I-AFIFUDIN-ZUHRI-001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11069\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/JUARA-I-AFIFUDIN-ZUHRI-001-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" \/><\/a> <a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/SERTIFIKAT-JUARA-II-AWPRO-CREATIVE-001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11070\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/SERTIFIKAT-JUARA-II-AWPRO-CREATIVE-001-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" \/><\/a><\/p>\n<p><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/sertifikat-bri-chalengge.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11135\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/sertifikat-bri-chalengge-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><\/a><\/p>\n<p><a href=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/lomba-video-edukasi_III.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11627\" src=\"https:\/\/mit.uin-malang.ac.id\/wp-content\/uploads\/2019\/09\/lomba-video-edukasi_III-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Congratulation for the achievement at BI Corner Challenge 3 that was held on 1 July-10 September 2019 is addressed to: Moch. Afifuddin Zuhri\/15650005 as 1st Winner on Design Challenge Fuad Jauhari \/15650067 &amp; Hagar Prily Titania\/16650031 as 2nd Winner on Design Challenge Muhammad Ammarullah Ridho\/17650071 as 3rd Winner on Design Challenge Adito Wahyu Prakoso \/17650081, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,71,27,103],"tags":[],"class_list":["post-11060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laboratory-of-multimedia","category-laboratory-of-hci","category-news","category-achievements"],"_links":{"self":[{"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/posts\/11060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/comments?post=11060"}],"version-history":[{"count":0,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/posts\/11060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/media?parent=11060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/categories?post=11060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mit.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/tags?post=11060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}